{"id":11253,"date":"2021-01-08T14:15:17","date_gmt":"2021-01-08T14:15:17","guid":{"rendered":"https:\/\/foysalfarabi.com\/woodmart\/product\/2020-new-benyar-top-brand-luxury-automatic-mechanical-mens-watches-men-fashion-waterproof-sport-watch-mens-watches-reloj-hombre\/"},"modified":"2021-01-08T14:15:22","modified_gmt":"2021-01-08T14:15:22","slug":"2020-new-benyar-top-brand-luxury-automatic-mechanical-mens-watches-men-fashion-waterproof-sport-watch-mens-watches-reloj-hombre","status":"publish","type":"product","link":"https:\/\/foysalfarabi.com\/woodmart\/product\/2020-new-benyar-top-brand-luxury-automatic-mechanical-mens-watches-men-fashion-waterproof-sport-watch-mens-watches-reloj-hombre\/","title":{"rendered":"2020 New BENYAR Top Brand Luxury Automatic Mechanical Men&#8217;s Watches Men Fashion Waterproof Sport Watch Mens Watches Reloj Hombre"},"content":{"rendered":"\n<div class=\"product-specs-list-container\">\n<ul class=\"product-specs-list util-clearfix\">\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Brand Name:&nbsp;<\/span><span class=\"property-desc line-limit-length\">BENYAR<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Water Resistance Depth:&nbsp;<\/span><span class=\"property-desc line-limit-length\">5Bar<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Origin:&nbsp;<\/span><span class=\"property-desc line-limit-length\">CN(Origin)<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Clasp Type:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Bracelet Clasp<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Style:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Fashion &amp; Casual<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Movement:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Automatic Self-Wind<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Band Length:&nbsp;<\/span><span class=\"property-desc line-limit-length\">24cm<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Case Material:&nbsp;<\/span><span class=\"property-desc line-limit-length\">STAINLESS STEEL<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Feature:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Shock Resistant<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Feature:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Water Resistant<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Feature:&nbsp;<\/span><span class=\"property-desc line-limit-length\">luminous hands<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Model Number:&nbsp;<\/span><span class=\"property-desc line-limit-length\">BY-5176<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Case Shape:&nbsp;<\/span><span class=\"property-desc line-limit-length\">ROUND<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Band Width:&nbsp;<\/span><span class=\"property-desc line-limit-length\">21mm<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Case Thickness:&nbsp;<\/span><span class=\"property-desc line-limit-length\">14mm<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Dial Window Material Type:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Hardlex<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Boxes &amp; Cases Material:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Paper<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Item Type:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Mechanical Wristwatches<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Dial Diameter:&nbsp;<\/span><span class=\"property-desc line-limit-length\">41mm<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Band Material Type:&nbsp;<\/span><span class=\"property-desc line-limit-length\">STAINLESS STEEL<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">LIGE watch:&nbsp;<\/span><span class=\"property-desc line-limit-length\">original brand<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">50ATM waterproof:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Super luminous (super long lasting)<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">2020 New Mechanical watch:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Automatic mechanical watch<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Tourbillon clock:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Automatic calendar<\/span>\n                            <\/li>\n<\/ul><\/div>\n<div class=\"detailmodule_dynamic\"><\/div>\n<div class=\"detailmodule_image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ae04.alicdn.com\/kf\/Hff0bcdd6b2d34770b3d469b2baea25fcZ.jpg?ssl=1\" class=\"detail-desc-decorate-image\" style=\"margin-bottom: 10px\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i1.wp.com\/ae04.alicdn.com\/kf\/H3cad5b57397d46788350792a5f3343f9w.jpg?ssl=1\" class=\"detail-desc-decorate-image\" style=\"margin-bottom: 10px\" data-recalc-dims=\"1\"><\/div>\n<div class=\"detailmodule_image\"><img decoding=\"async\" src=\"https:\/\/i2.wp.com\/ae01.alicdn.com\/kf\/H545ee2d9bcc64ff6b00a6e0bd3794e7aX.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><\/div>\n<div class=\"detailmodule_image\"><img decoding=\"async\" src=\"https:\/\/i2.wp.com\/ae01.alicdn.com\/kf\/Hb71c5ad19ec04e5cb854275933d91b18v.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><\/div>\n<div class=\"detailmodule_image\"><img decoding=\"async\" src=\"https:\/\/i1.wp.com\/ae01.alicdn.com\/kf\/Hbc89f49e938f445d8ac0166e86f78734H.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><\/div>\n<div class=\"detailmodule_image\"><img decoding=\"async\" src=\"https:\/\/i2.wp.com\/ae01.alicdn.com\/kf\/Hc15d2a0a72b34541995fedfece2810a66.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><\/div>\n<div class=\"detailmodule_image\"><img decoding=\"async\" src=\"https:\/\/i1.wp.com\/ae01.alicdn.com\/kf\/H7d008e0e41a840459b6dc5107adf8c55d.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><\/div>\n<div class=\"detailmodule_image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ae04.alicdn.com\/kf\/Hed8c16497acb44bdac3c7218e302351cL.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i1.wp.com\/ae04.alicdn.com\/kf\/H64d9824b40414581bc3a2da71e669f34Z.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i2.wp.com\/ae04.alicdn.com\/kf\/H26eb4ee29fd34d7ca9775eee5bf8cd8au.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ae04.alicdn.com\/kf\/H8bbc621f9c784a39a53107ea9271c1d38.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i1.wp.com\/ae04.alicdn.com\/kf\/Ha17da863f66d42328eda93bf4490f454m.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i2.wp.com\/ae04.alicdn.com\/kf\/Ha0632c4e2dba43778b59290cf584af418.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i2.wp.com\/ae04.alicdn.com\/kf\/H1893d50b15994ae2a78c61b2536fc22cq.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ae04.alicdn.com\/kf\/Hfc978d24c71741a2ac1df851f503db6fR.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i2.wp.com\/ae04.alicdn.com\/kf\/Hf43b96f26a444936bfd60df7cd81470bd.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i2.wp.com\/ae04.alicdn.com\/kf\/H4402ee16aa454fa4bfb1759fbe7cb53fu.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><\/div>\n<div class=\"detailmodule_image\"><img decoding=\"async\" src=\"https:\/\/i2.wp.com\/ae04.alicdn.com\/kf\/H671390e731de4f98bdb24db130c9f458X.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i1.wp.com\/ae04.alicdn.com\/kf\/Hc8e727cd9bc64a24ba4e7ff27bd60695P.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/ae04.alicdn.com\/kf\/Hac67ac46568b43bd8659a476379651b4f.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><img decoding=\"async\" src=\"https:\/\/i1.wp.com\/ae04.alicdn.com\/kf\/Hf302895b0fed461ebbf0d77747d3dc43U.jpg?ssl=1\" class=\"detail-desc-decorate-image\" data-recalc-dims=\"1\"><\/div>\n<div class=\"detailmodule_dynamic\"><\/div>\n<div class=\"detailmodule_text\">\n<p class=\"detail-desc-decorate-content\" style=\"font-family: 'OpenSans';color:'#000';font-weight: 300;font-size: 14px;line-height: 20px;color: #000;margin-bottom: 12px\"> \u00a0 <\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Brand Name:&nbsp;BENYAR Water Resistance Depth:&nbsp;5Bar Origin:&nbsp;CN(Origin) Clasp Type:&nbsp;Bracelet Clasp Style:&nbsp;Fashion &amp; Casual Movement:&nbsp;Automatic Self-Wind Band Length:&nbsp;24cm Case Material:&nbsp;STAINLESS STEEL Feature:&nbsp;Shock<\/p>\n","protected":false},"featured_media":11254,"comment_status":"open","ping_status":"closed","template":"","meta":{"spay_email":""},"class_list":["post-11253","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-mens-watches","product_cat-watches"],"_links":{"self":[{"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/product\/11253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/comments?post=11253"}],"version-history":[{"count":0,"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/product\/11253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/media\/11254"}],"wp:attachment":[{"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/media?parent=11253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}