{"id":12004,"date":"2021-01-08T14:41:57","date_gmt":"2021-01-08T14:41:57","guid":{"rendered":"https:\/\/foysalfarabi.com\/woodmart\/product\/hot-sale-original-iphone-5-a5-factory-unlocked-cell-phone-ios-dual-core-1g-ram-16gb-32gb-64gb-rom-4-0-8mp-camera-wifi-3g-gps\/"},"modified":"2021-01-08T14:42:03","modified_gmt":"2021-01-08T14:42:03","slug":"hot-sale-original-iphone-5-a5-factory-unlocked-cell-phone-ios-dual-core-1g-ram-16gb-32gb-64gb-rom-4-0-8mp-camera-wifi-3g-gps","status":"publish","type":"product","link":"https:\/\/foysalfarabi.com\/woodmart\/product\/hot-sale-original-iphone-5-a5-factory-unlocked-cell-phone-ios-dual-core-1g-ram-16gb-32gb-64gb-rom-4-0-8mp-camera-wifi-3g-gps\/","title":{"rendered":"Hot sale Original Iphone 5 A5 Factory Unlocked Cell Phone iOS Dual core 1G RAM 16GB 32GB 64GB ROM 4.0&#8242; 8MP Camera WIFI 3G GPS"},"content":{"rendered":"\n<div class=\"product-specs-list-container\">\n<ul class=\"product-specs-list util-clearfix\">\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Brand Name:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">APPLE<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Apple Model:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">iPhone 5<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Battery Type:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Not Detachable<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">ROM:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">16G<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Item Condition:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Used<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Operation System:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">ios<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Biometrics Technology:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">No<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Standby Time:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Up To 120 Hours<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Front Camera Quantity:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">1<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Rear Camera Pixel:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">8MP<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Battery Capacity(mAh):&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">1440mah<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Fast Charging:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Nonsupport<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Phone Type:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Smart Phones<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Touch Screen Type:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Capacitive Screen<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Language:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Norwegian<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Language:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Russian<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Language:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Italian<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Language:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">German<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Language:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">French<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Language:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Spanish<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Language:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">POLISH<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Language:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Turkish<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Language:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Portuguese<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Language:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">english<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Optical Zoom:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">No<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Display Resolution:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">640&#215;1136<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Rear Camera Quantity:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">1<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Charging Interface Type:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Linghting<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Front Camera Pixel:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Other<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Wireless Charging:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">No<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Design:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">BAR<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">SIM Card Quantity:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">1 SIM Card<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Display Size:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">4.0<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">3.5mm Headphone Port:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Yes<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Screen Type:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Normal Screen<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">RAM:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">1G<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Unlock Phones:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">Yes<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Screen Material:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">IPS<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span\n                                        class=\"property-title\">Release Date:&nbsp;<\/span><span\n                                        class=\"property-desc line-limit-length\">2012<\/span>\n                            <\/li>\n<\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Brand Name:&nbsp;APPLE Apple Model:&nbsp;iPhone 5 Battery Type:&nbsp;Not Detachable ROM:&nbsp;16G Item Condition:&nbsp;Used Operation System:&nbsp;ios Biometrics Technology:&nbsp;No Standby Time:&nbsp;Up To 120 Hours<\/p>\n","protected":false},"featured_media":12006,"comment_status":"open","ping_status":"closed","template":"","meta":{"spay_email":""},"class_list":["post-12004","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-iphone","product_cat-phones"],"_links":{"self":[{"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/product\/12004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/comments?post=12004"}],"version-history":[{"count":0,"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/product\/12004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/media\/12006"}],"wp:attachment":[{"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/media?parent=12004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}