{"id":12155,"date":"2021-01-08T14:47:43","date_gmt":"2021-01-08T14:47:43","guid":{"rendered":"https:\/\/foysalfarabi.com\/woodmart\/product\/2020-new-apple-iphone-se-2-mobile-phone-4-7-3gb-ram-64g-128g-256gb-rom-ios-13-nfc-wireless-charge-iphone-se-a2296-smart-phone\/"},"modified":"2021-01-08T14:47:47","modified_gmt":"2021-01-08T14:47:47","slug":"2020-new-apple-iphone-se-2-mobile-phone-4-7-3gb-ram-64g-128g-256gb-rom-ios-13-nfc-wireless-charge-iphone-se-a2296-smart-phone","status":"publish","type":"product","link":"https:\/\/foysalfarabi.com\/woodmart\/product\/2020-new-apple-iphone-se-2-mobile-phone-4-7-3gb-ram-64g-128g-256gb-rom-ios-13-nfc-wireless-charge-iphone-se-a2296-smart-phone\/","title":{"rendered":"2020 New Apple iphone SE 2 Mobile Phone 4.7&#8243; 3GB RAM 64G\/128G\/256GB ROM iOS 13 NFC wireless charge iphone SE A2296 Smart Phone"},"content":{"rendered":"\n<div class=\"product-specs-list-container\">\n<ul class=\"product-specs-list util-clearfix\">\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Brand Name:&nbsp;<\/span><span class=\"property-desc line-limit-length\">APPLE<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Apple Model:&nbsp;<\/span><span class=\"property-desc line-limit-length\">iPhone SE<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Battery Type:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Not Detachable<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">ROM:&nbsp;<\/span><span class=\"property-desc line-limit-length\">256G<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Item Condition:&nbsp;<\/span><span class=\"property-desc line-limit-length\">New<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Operation System:&nbsp;<\/span><span class=\"property-desc line-limit-length\">ios<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Biometrics Technology:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Fingerprint Recognition<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Standby Time:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Other<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Front Camera Quantity:&nbsp;<\/span><span class=\"property-desc line-limit-length\">1<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Rear Camera Pixel:&nbsp;<\/span><span class=\"property-desc line-limit-length\">12MP<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Battery Capacity(mAh):&nbsp;<\/span><span class=\"property-desc line-limit-length\">1821<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Fast Charging:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Adaptive Fast Charge<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Phone Type:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Smart Phones<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Touch Screen Type:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Capacitive Screen<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Language:&nbsp;<\/span><span class=\"property-desc line-limit-length\">english<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Language:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Russian<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Language:&nbsp;<\/span><span class=\"property-desc line-limit-length\">German<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Language:&nbsp;<\/span><span class=\"property-desc line-limit-length\">French<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Language:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Spanish<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Language:&nbsp;<\/span><span class=\"property-desc line-limit-length\">POLISH<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Language:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Portuguese<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Language:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Italian<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Language:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Korean<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Language:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Japanese<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Language:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Arabic<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Optical Zoom:&nbsp;<\/span><span class=\"property-desc line-limit-length\">No<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Display Resolution:&nbsp;<\/span><span class=\"property-desc line-limit-length\">750 x 1334px<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Rear Camera Quantity:&nbsp;<\/span><span class=\"property-desc line-limit-length\">1<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Charging Interface Type:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Mini USB<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Front Camera Pixel:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Other<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Wireless Charging:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Yes<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Design:&nbsp;<\/span><span class=\"property-desc line-limit-length\">BAR<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">SIM Card Quantity:&nbsp;<\/span><span class=\"property-desc line-limit-length\">1 SIM Card<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Display Size:&nbsp;<\/span><span class=\"property-desc line-limit-length\">4.7<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">3.5mm Headphone Port:&nbsp;<\/span><span class=\"property-desc line-limit-length\">No<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Screen Type:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Other<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Cellular:&nbsp;<\/span><span class=\"property-desc line-limit-length\">GSM<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Cellular:&nbsp;<\/span><span class=\"property-desc line-limit-length\">CDMA<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Cellular:&nbsp;<\/span><span class=\"property-desc line-limit-length\">WCDMA<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Cellular:&nbsp;<\/span><span class=\"property-desc line-limit-length\">LTE<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Display Proportions:&nbsp;<\/span><span class=\"property-desc line-limit-length\">16:9<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">CPU Model:&nbsp;<\/span><span class=\"property-desc line-limit-length\">APPLE<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Apple Model:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Apple A13 Bionic<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">NFC:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Yes<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">RAM:&nbsp;<\/span><span class=\"property-desc line-limit-length\">3G<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Unlock Phones:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Yes<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Screen Material:&nbsp;<\/span><span class=\"property-desc line-limit-length\">IPS<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">CPU Core Quantity:&nbsp;<\/span><span class=\"property-desc line-limit-length\">Hexa Core<\/span>\n                            <\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">Release Date:&nbsp;<\/span><span class=\"property-desc line-limit-length\">2020<\/span>\n                            <\/li>\n<\/ul><\/div>\n<div class=\"detailmodule_dynamic\"><\/div>\n<div class=\"detailmodule_html\">\n<div class=\"detail-desc-decorate-richtext\">\n<p>\n\t<img decoding=\"async\" alt=\"PC\u8be6\u60c5_01\" src=\"https:\/\/i2.wp.com\/ae01.alicdn.com\/kf\/H585f0b6c183d47a6ba72e12ca391ed5a7.jpg?ssl=1\" data-recalc-dims=\"1\" \/><img decoding=\"async\" alt=\"PC\u8be6\u60c5_02\" src=\"https:\/\/i2.wp.com\/ae01.alicdn.com\/kf\/H9f02330f11f049c9a01aa350ec7fe754h.jpg?ssl=1\" data-recalc-dims=\"1\" \/><img decoding=\"async\" alt=\"PC\u8be6\u60c5_04\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Had2342ef085946c4adaa3c467fc677ecN.jpg?ssl=1\" data-recalc-dims=\"1\" \/>\n<\/p>\n<\/div>\n<\/div>\n<div class=\"detailmodule_html\">\n<div class=\"detail-desc-decorate-richtext\">\n<p>\n\t<img decoding=\"async\" alt=\"\u672a\u6807\u9898-1_01\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/H970ee7cf638447cbb315f73f18283c83P.jpg?ssl=1\" data-recalc-dims=\"1\" \/>\n<\/p>\n<\/div>\n<\/div>\n<div class=\"detailmodule_html\">\n<div class=\"detail-desc-decorate-richtext\">\n<p>\n\t&nbsp;\n<\/p>\n<p>\n\t&nbsp;\n<\/p>\n<\/div>\n<\/div>\n<div class=\"detailmodule_html\">\n<div class=\"detail-desc-decorate-richtext\">\n<p>\n\t<img decoding=\"async\" alt=\"11\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/H4d0dd9b195004e14b0624cc38d6d1dbar.jpg?ssl=1\" data-recalc-dims=\"1\" \/><img decoding=\"async\" alt=\"12\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Hf1111ce45aae40bd87171616e530c369a.jpg?ssl=1\" data-recalc-dims=\"1\" \/><img decoding=\"async\" alt=\"13\" src=\"https:\/\/i2.wp.com\/ae01.alicdn.com\/kf\/Hf6bf9cb31cb646f3bc4510b2c9543b68O.jpg?ssl=1\" data-recalc-dims=\"1\" \/><img decoding=\"async\" alt=\"14\" src=\"https:\/\/i2.wp.com\/ae01.alicdn.com\/kf\/H75d1a3b813ab4d8d80c3f5e24faf4b01y.jpg?ssl=1\" data-recalc-dims=\"1\" \/><img decoding=\"async\" alt=\"15\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/H073d87a2981e4c9eb646944f43fca14es.jpg?ssl=1\" data-recalc-dims=\"1\" \/>\n<\/p>\n<\/div>\n<\/div>\n<div class=\"detailmodule_dynamic\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Brand Name:&nbsp;APPLE Apple Model:&nbsp;iPhone SE Battery Type:&nbsp;Not Detachable ROM:&nbsp;256G Item Condition:&nbsp;New Operation System:&nbsp;ios Biometrics Technology:&nbsp;Fingerprint Recognition Standby Time:&nbsp;Other Front Camera<\/p>\n","protected":false},"featured_media":12156,"comment_status":"open","ping_status":"closed","template":"","meta":{"spay_email":""},"class_list":["post-12155","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-iphone","product_cat-phones"],"_links":{"self":[{"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/product\/12155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/comments?post=12155"}],"version-history":[{"count":0,"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/product\/12155\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/media\/12156"}],"wp:attachment":[{"href":"https:\/\/foysalfarabi.com\/woodmart\/wp-json\/wp\/v2\/media?parent=12155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}